{"id":363,"date":"2020-04-14T11:21:31","date_gmt":"2020-04-14T10:21:31","guid":{"rendered":"http:\/\/blog.eventoempresabcn.es\/?p=363"},"modified":"2026-01-14T14:33:19","modified_gmt":"2026-01-14T13:33:19","slug":"beneficios-de-sonreir-en-tiempos-de-crisis","status":"publish","type":"post","link":"https:\/\/eventoempresa.com\/ca\/beneficios-de-sonreir-en-tiempos-de-crisis\/","title":{"rendered":"Beneficios de sonre\u00edr en tiempos de crisis"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sobrellevar las dificultades, tener<strong> un nuevo enfoque <\/strong>sobre la situaci\u00f3n&nbsp;en la que te encuentras,  as\u00ed como mejorar tu capacidad resolutiva&nbsp;y reducir el estr\u00e9s; son algunos de los beneficios de sonre\u00edr en tiempos de crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sigue estos consejos para experimentar los beneficios de sonre\u00edr:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Haz de la sonrisa un prop\u00f3sito diario.&nbsp;<\/li><li>Piensa en situaciones y experiencias que te hagan feliz, viaja en tus recuerdos y llega al destino ubicando el momento en que te sentiste feliz.&nbsp;<\/li><li>Ten pensamientos alegres,&nbsp;pensando en las personas que quieres, tus afectos.&nbsp;<\/li><li>Presta mayor atenci\u00f3n en las personas que sonr\u00eden, observar\u00e1s que trasladan una energ\u00eda positiva que contagia.&nbsp;<\/li><li> Busca un detonador, una palabra,&nbsp;un gesto que te ayude a que esa sonrisa natural se dibuje en tu rostro.&nbsp; <\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_301416947-1024x683.jpg\" alt=\"Busca razones para dibujar en tu rostro una sonrisa.\" class=\"wp-image-5672\" srcset=\"https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_301416947-1024x683.jpg 1024w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_301416947-300x200.jpg 300w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_301416947-768x512.jpg 768w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_301416947-600x400.jpg 600w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_301416947-1080x720.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Busca razones para dibujar en tu rostro una sonrisa.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Descubre algunos juegos y din\u00e1micas para sonre\u00edr en tiempos de crisis:&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El ba\u00fal m\u00e1gico:<\/strong>&nbsp;coloca objetos en una caja o bolsa, por ejemplo: pelota, manta, bol\u00edgrafo, servilleta, lo que desees guardar.&nbsp;Con cada uno de ellos, tendr\u00e1s que realizar una peque\u00f1a m\u00edmica, pero\u2026 \u00a1magia! Tendr\u00e1s que dar a cada objeto otra utilidad distinta a la que tiene, por ejemplo: La servilleta es un libro de cuentos de magia, la pelota es ahora un globo aerost\u00e1tico que te permite viajar; el bol\u00edgrafo se ha convertido en una escoba. El que adivine en qu\u00e9 se ha convertido el objeto en la caja o bolsa m\u00e1gica gana el juego.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La pantomima:<\/strong>&nbsp;en 5 minutos controlados por reloj, debes representar mediante m\u00edmica una acci\u00f3n de la vida cotidiana, por ejemplo: cocinar una tortilla de&nbsp;patatas, ir al trabajo o un cumplea\u00f1os de&nbsp;un integrante de&nbsp;la familia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Adivina la pel\u00edcula:<\/strong>&nbsp;consiste en que hagas una representaci\u00f3n gestual del t\u00edtulo de una pel\u00edcula. Como variantes del juego en esa representaci\u00f3n, puedes hacer alg\u00fan personaje o escena central que lleve a adivinar el t\u00edtulo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nombres de personalidades:&nbsp;<\/strong>imita a celebridades; por ejemplo: Elvis Presley, Tom&nbsp;Hanks, Rosal\u00eda. Lo m\u00e1s importante es buscar nombres que sean divertidos de imitar y que te obligue a esforzarte en la imitaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"678\" src=\"https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_1351388609-1024x678.jpg\" alt=\"Descubre algunos juegos y din\u00e1micas para sonre\u00edr en tiempos de crisis.\" class=\"wp-image-5678\" srcset=\"https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_1351388609-1024x678.jpg 1024w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_1351388609-300x199.jpg 300w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_1351388609-768x509.jpg 768w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_1351388609-600x397.jpg 600w, https:\/\/eventoempresa.com\/wp-content\/uploads\/2020\/04\/shutterstock_1351388609-1080x715.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>Descubre algunos juegos y din\u00e1micas para sonre\u00edr en tiempos de crisis.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Lo m\u00e1s importante, que tu expresi\u00f3n lo diga todo:&nbsp;<strong>\u00a1Sonr\u00ede!&nbsp;<\/strong> <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aprendemos juntos, #TodoIr\u00e1Bien&nbsp;#Qu\u00e9dateEnCasa<\/strong>&nbsp; <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u00abUna sonrisa cuesta poco, sin embargo, vale mucho. Quien la da es feliz y quien la recibe la agradece. Dura solo un instante y su recuerdo, a veces, perdura toda una vida\u00bb<\/em>&nbsp;<br><\/p><cite>Mariano Aguirre<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora que ya conoces las claves para sonre\u00edr, ponlas en pr\u00e1ctica y <a href=\"https:\/\/eventoempresa.com\/contacto\/\">contacta a nuestro equipo de especialistas<\/a> para solicitar una asesor\u00eda personalizada que te ayude a salir adelante en esta situaci\u00f3n con tu familia y equipo.  \u00a1Recuerda que es tiempo de sonre\u00edr e impulsar tu actitud  positiva! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes de apoyo consultadas:  <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u201cLas peque\u00f1as alegr\u00edas\u201d, Marc&nbsp;Aug\u00e9.&nbsp;<\/li><li>\u201cSer feliz y vencer las preocupaciones\u201d, Albert Ellis.&nbsp;<\/li><li>\u201cSer feliz es una decisi\u00f3n\u201d, John&nbsp;Leland.&nbsp;<\/li><li><a href=\"https:\/\/es.scribd.com\/document\/412652754\/El-Poder-de-Una-Sonrisa\">\u201cEl Poder de Una Sonrisa\u201d, Dra. Emilia O\u2019Neill-Baker (Psic\u00f3loga y&nbsp;Psicoterapeuta Gestalt).<\/a>&nbsp;<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sobrellevar las dificultades, tener un nuevo enfoque sobre la situaci\u00f3n&nbsp;en la que te encuentras, as\u00ed como mejorar tu capacidad resolutiva&nbsp;y reducir el estr\u00e9s; son algunos de los beneficios de sonre\u00edr en tiempos de crisis. Sigue estos consejos para experimentar los beneficios de sonre\u00edr:&nbsp; Haz de la sonrisa un prop\u00f3sito diario.&nbsp; Piensa en situaciones y experiencias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[560],"tags":[],"class_list":["post-363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-blog"],"_links":{"self":[{"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/posts\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/comments?post=363"}],"version-history":[{"count":33,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/posts\/363\/revisions"}],"predecessor-version":[{"id":5966,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/posts\/363\/revisions\/5966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/media\/5669"}],"wp:attachment":[{"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/media?parent=363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/categories?post=363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eventoempresa.com\/ca\/wp-json\/wp\/v2\/tags?post=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}